{"id":37079,"date":"2026-07-20T12:27:36","date_gmt":"2026-07-20T15:27:36","guid":{"rendered":"https:\/\/betterpros.com\/careers\/?post_type=product&#038;p=37079"},"modified":"2026-07-20T12:28:36","modified_gmt":"2026-07-20T15:28:36","slug":"responsable-de-redes-sociales-flex-florida","status":"publish","type":"product","link":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/","title":{"rendered":"responsable de redes sociales (Flex, Florida)"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"content-type":"","footnotes":""},"product_brand":[],"product_cat":[747,231],"product_tag":[],"framework":[],"expertise":[],"field":[],"software":[],"product-category":[],"class_list":["post-37079","product","type-product","status-publish","product_cat-marketing-digital","product_cat-marketing-y-creatividad","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>responsable de redes sociales (Flex, Florida)<\/title>\n<meta name=\"description\" content=\"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"responsable de redes sociales (Flex, Florida)\" \/>\n<meta property=\"og:description\" content=\"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/\" \/>\n<meta property=\"og:site_name\" content=\"Careers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Better-Pros-105415752069554\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T15:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/betterpros.com\/careers\/wp-content\/uploads\/2023\/05\/gif-carrer-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/responsable-de-redes-sociales-flex-florida\\\/\",\"url\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/responsable-de-redes-sociales-flex-florida\\\/\",\"name\":\"responsable de redes sociales (Flex, Florida)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#website\"},\"datePublished\":\"2026-07-20T15:27:36+00:00\",\"dateModified\":\"2026-07-20T15:28:36+00:00\",\"description\":\"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/responsable-de-redes-sociales-flex-florida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/responsable-de-redes-sociales-flex-florida\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/responsable-de-redes-sociales-flex-florida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carreras\",\"item\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/career\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marketing y Creatividad\",\"item\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/marketing-y-creatividad\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"responsable de redes sociales (Flex, Florida)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/\",\"name\":\"BetterPros Careers\",\"description\":\"Find a job in BetterPros Career Site\",\"publisher\":{\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#organization\",\"name\":\"BetterPros Careers\",\"url\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/betterpros-logo.png\",\"contentUrl\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/betterpros-logo.png\",\"width\":1666,\"height\":491,\"caption\":\"BetterPros Careers\"},\"image\":{\"@id\":\"https:\\\/\\\/betterpros.com\\\/careers\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Better-Pros-105415752069554\",\"https:\\\/\\\/www.instagram.com\\\/betterpros\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/betterpros\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"responsable de redes sociales (Flex, Florida)","description":"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/","og_locale":"es_ES","og_type":"article","og_title":"responsable de redes sociales (Flex, Florida)","og_description":"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.","og_url":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/","og_site_name":"Careers","article_publisher":"https:\/\/www.facebook.com\/Better-Pros-105415752069554","article_modified_time":"2026-07-20T15:28:36+00:00","og_image":[{"url":"https:\/\/betterpros.com\/careers\/wp-content\/uploads\/2023\/05\/gif-carrer-1.gif","width":720,"height":405,"type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/","url":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/","name":"responsable de redes sociales (Flex, Florida)","isPartOf":{"@id":"https:\/\/betterpros.com\/careers\/es\/#website"},"datePublished":"2026-07-20T15:27:36+00:00","dateModified":"2026-07-20T15:28:36+00:00","description":"Post\u00falate al puesto flexible de Community Manager en Florida. Gestiona comunidades digitales, ejecuta estrategias de redes sociales enfocadas en el sector AEC e impulsa la interacci\u00f3n para profesionales de la ingenier\u00eda y arquitectura.","breadcrumb":{"@id":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/responsable-de-redes-sociales-flex-florida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/betterpros.com\/careers\/es\/"},{"@type":"ListItem","position":2,"name":"Carreras","item":"https:\/\/betterpros.com\/careers\/es\/career\/"},{"@type":"ListItem","position":3,"name":"Marketing y Creatividad","item":"https:\/\/betterpros.com\/careers\/es\/marketing-y-creatividad\/"},{"@type":"ListItem","position":4,"name":"responsable de redes sociales (Flex, Florida)"}]},{"@type":"WebSite","@id":"https:\/\/betterpros.com\/careers\/es\/#website","url":"https:\/\/betterpros.com\/careers\/es\/","name":"BetterPros Careers","description":"Find a job in BetterPros Career Site","publisher":{"@id":"https:\/\/betterpros.com\/careers\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/betterpros.com\/careers\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/betterpros.com\/careers\/es\/#organization","name":"BetterPros Careers","url":"https:\/\/betterpros.com\/careers\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/betterpros.com\/careers\/es\/#\/schema\/logo\/image\/","url":"https:\/\/betterpros.com\/careers\/wp-content\/uploads\/2023\/03\/betterpros-logo.png","contentUrl":"https:\/\/betterpros.com\/careers\/wp-content\/uploads\/2023\/03\/betterpros-logo.png","width":1666,"height":491,"caption":"BetterPros Careers"},"image":{"@id":"https:\/\/betterpros.com\/careers\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Better-Pros-105415752069554","https:\/\/www.instagram.com\/betterpros\/","https:\/\/www.linkedin.com\/company\/betterpros\/"]}]}},"_links":{"self":[{"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product\/37079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product\/37079\/revisions"}],"predecessor-version":[{"id":37083,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product\/37079\/revisions\/37083"}],"wp:attachment":[{"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/media?parent=37079"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product_brand?post=37079"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product_cat?post=37079"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product_tag?post=37079"},{"taxonomy":"framework","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/framework?post=37079"},{"taxonomy":"expertise","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/expertise?post=37079"},{"taxonomy":"field","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/field?post=37079"},{"taxonomy":"software","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/software?post=37079"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/betterpros.com\/careers\/es\/wp-json\/wp\/v2\/product-category?post=37079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}